{"id":8274,"date":"2026-02-03T09:20:54","date_gmt":"2026-02-03T08:20:54","guid":{"rendered":"https:\/\/barcelone.centre-pensees.com\/?page_id=8274"},"modified":"2026-03-23T15:58:03","modified_gmt":"2026-03-23T14:58:03","slug":"maria-marti-psicologa-de-habla-hispana-e-inglesa-en-barcelona","status":"publish","type":"page","link":"https:\/\/barcelone.centre-pensees.com\/es\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/","title":{"rendered":"Mar\u00eda Mart\u00ed Psic\u00f3loga de habla hispana e inglesa en Barcelona"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_direction=\u00a0\u00bb200deg\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(0,0,0,0) 66%|rgba(22,29,67,0.3) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb background_color_gradient_start_position=\u00a0\u00bb62%\u00a0\u00bb background_color_gradient_end=\u00a0\u00bbrgba(22,29,67,0.3)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2022\/06\/1.jpg\u00a0\u00bb custom_padding=\u00a0\u00bb9vw|10vw|0vw|0px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|10vw||\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb animation_starting_opacity=\u00a0\u00bb5%\u00a0\u00bb animation_speed_curve=\u00a0\u00bbease-out\u00a0\u00bb custom_css_main_element=\u00a0\u00bbbackground-attachment: fixed;||background-position: 50% 100%;\u00a0\u00bb border_radii=\u00a0\u00bb||||16vw\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb3_4,1_4&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb padding_top_bottom_link_1=\u00a0\u00bbtrue\u00a0\u00bb padding_top_bottom_link_2=\u00a0\u00bbtrue\u00a0\u00bb padding_left_right_link_1=\u00a0\u00bbfalse\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_direction=\u00a0\u00bb90deg\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(255,255,255,0.4) 70%|rgba(255,255,255,0.88) 100%\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(255,255,255,0.4)\u00a0\u00bb background_color_gradient_start_position=\u00a0\u00bb70%\u00a0\u00bb background_color_gradient_end=\u00a0\u00bbrgba(255,255,255,0.88)\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb module_alignment=\u00a0\u00bbleft\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0vw|||\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|||0vw\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbleft\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb5%\u00a0\u00bb border_radii=\u00a0\u00bb||10vw||\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb80px|40px|80px|10vw\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb40px||20px||false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|||\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb padding_phone=\u00a0\u00bb|||\u00a0\u00bb padding_tablet=\u00a0\u00bb40px||20px||false\u00a0\u00bb padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; header_font=\u00a0\u00bbPrata||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#000000&Prime; header_font_size=\u00a0\u00bb100px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb header_6_font=\u00a0\u00bbOpen Sans|700||on|||||\u00a0\u00bb header_6_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_6_line_height=\u00a0\u00bb1.6em\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb width=\u00a0\u00bb99.9%\u00a0\u00bb max_width_tablet=\u00a0\u00bb90%\u00a0\u00bb max_width_phone=\u00a0\u00bb\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb module_alignment=\u00a0\u00bbright\u00a0\u00bb custom_margin=\u00a0\u00bb|-236px||||\u00a0\u00bb animation_style=\u00a0\u00bbzoom\u00a0\u00bb animation_intensity_zoom=\u00a0\u00bb5%\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb48px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb32px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_6_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_6_font_size_phone=\u00a0\u00bb\u00a0\u00bb header_6_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb text_text_shadow_style=\u00a0\u00bbpreset3&Prime; text_text_shadow_blur_strength=\u00a0\u00bb3em\u00a0\u00bb text_text_shadow_color=\u00a0\u00bbrgba(22,29,67,0.24)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb header_5_font_size__hover=\u00a0\u00bb16px\u00a0\u00bb header_5_font_size__hover_enabled=\u00a0\u00bb16px\u00a0\u00bb header_5_letter_spacing__hover=\u00a0\u00bb0px\u00a0\u00bb header_5_letter_spacing__hover_enabled=\u00a0\u00bb0px\u00a0\u00bb header_5_line_height__hover=\u00a0\u00bb1em\u00a0\u00bb header_5_line_height__hover_enabled=\u00a0\u00bb1em\u00a0\u00bb header_5_text_shadow_style__hover=\u00a0\u00bbnone\u00a0\u00bb header_5_text_shadow_style__hover_enabled=\u00a0\u00bbnone\u00a0\u00bb header_5_text_shadow_color__hover=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb header_5_text_shadow_color__hover_enabled=\u00a0\u00bbrgba(0,0,0,0.4)\u00a0\u00bb]<\/p>\n<p>Centre Pens\u00e9es &#8211; Centre International de th\u00e9rapie \u00e0 Barcelone<\/p>\n<h1>Mar\u00eda Mart\u00ed<\/h1>\n<div data-sentry-element=\"Container\" data-sentry-component=\"QuestionAnswer\" data-sentry-source-file=\"index.tsx\" class=\"sc-7cef46a6-0 dfFUpr\">Psychoth\u00e9rapie int\u00e9grative, th\u00e9rapie pour adultes et adolescents<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||||false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb padding_tablet=\u00a0\u00bb||||false\u00a0\u00bb padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb padding_phone=\u00a0\u00bb||||false\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb10px|auto||auto||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p data-start=\"154\" data-end=\"463\">Je suis psychoth\u00e9rapeute et je travaille \u00e0 partir d\u2019une approche humaniste et <a href=\"https:\/\/barcelone.centre-pensees.com\/la-therapie-integrative\/\" target=\"_blank\" rel=\"noopener\">i<\/a><a href=\"https:\/\/barcelone.centre-pensees.com\/la-therapie-integrative\/\">nt\u00e9grative,<\/a> avec un fort ancrage relationnel. J\u2019accompagne des personnes en espagnol et en anglais, et je travaille avec des client\u00b7e\u00b7s locaux et internationaux, dont beaucoup vivent entre plusieurs cultures, langues et identit\u00e9s.<\/p>\n<p data-start=\"465\" data-end=\"917\">Je crois que le processus de gu\u00e9rison se d\u00e9ploie au sein de relations s\u00fbres et authentiques. Dans mon travail, j\u2019accorde une importance centrale \u00e0 la cr\u00e9ation d\u2019un espace th\u00e9rapeutique dans lequel chacun\u00b7e peut se sentir vu\u00b7e, respect\u00e9\u00b7e et libre d\u2019explorer son monde int\u00e9rieur \u00e0 son propre rythme. J\u2019adopte une pr\u00e9sence chaleureuse, engag\u00e9e et non jugeante, et j\u2019utilise la relation th\u00e9rapeutique elle-m\u00eame comme un levier essentiel de transformation.<\/p>\n<p data-start=\"919\" data-end=\"1292\">J\u2019int\u00e8gre dans mes s\u00e9ances l\u2019exploration \u00e9motionnelle, la conscience corporelle et le dialogue. Lorsque cela soutient le processus, j\u2019utilise \u00e9galement des ressources cr\u00e9atives et r\u00e9flexives \u2014 comme l\u2019\u00e9criture ou des pratiques simples et concr\u00e8tes \u2014 afin de permettre l\u2019acc\u00e8s et l\u2019expression d\u2019exp\u00e9riences int\u00e9rieures parfois difficiles \u00e0 atteindre uniquement par les mots.<\/p>\n<p data-start=\"1294\" data-end=\"1665\">Je porte une attention particuli\u00e8re aux enjeux li\u00e9s \u00e0 la migration, \u00e0 l\u2019identit\u00e9, \u00e0 l\u2019attachement, aux traumatismes relationnels, \u00e0 l\u2019estime de soi, au deuil et \u00e0 la r\u00e9gulation \u00e9motionnelle. Plut\u00f4t que de m\u2019appuyer sur des techniques fig\u00e9es, j\u2019adapte mon accompagnement aux besoins sp\u00e9cifiques de chaque personne, en respectant l\u2019unicit\u00e9 de chaque parcours th\u00e9rapeutique.<\/p>\n<p data-start=\"1667\" data-end=\"1994\">Dans mon espace th\u00e9rapeutique, les personnes peuvent s\u2019attendre \u00e0 un cadre qui valorise l\u2019honn\u00eatet\u00e9, la profondeur et la compassion. J\u2019accompagne mes client\u00b7e\u00b7s dans la reconnexion \u00e0 eux-m\u00eames, la compr\u00e9hension de leurs dynamiques relationnelles et le d\u00e9veloppement d\u2019un lien plus accueillant et ancr\u00e9 \u00e0 leur propre exp\u00e9rience.<\/p>\n<p data-start=\"1996\" data-end=\"2209\">Pour moi, la th\u00e9rapie n\u2019a pas pour objectif de \u00ab r\u00e9parer \u00bb une personne, mais d\u2019offrir une pr\u00e9sence et un accompagnement pour donner du sens \u00e0 son histoire et cultiver une mani\u00e8re d\u2019\u00eatre au monde plus authentique.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2026\/02\/foto-psicologia-barcelona-psychologist-barcelona.jpg\u00a0\u00bb alt=\u00a0\u00bbjudith escardo psychologue barcelone\u00a0\u00bb title_text=\u00a0\u00bbfoto-psicologia-barcelona-psychologist-barcelona\u00a0\u00bb force_fullwidth=\u00a0\u00bbon\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; custom_margin=\u00a0\u00bb26px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbright\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb5%\u00a0\u00bb border_radii=\u00a0\u00bboff|4vw|4vw|4vw|24vw\u00a0\u00bb border_color_all=\u00a0\u00bbrgba(117,210,197,0.45)\u00a0\u00bb border_width_left=\u00a0\u00bb1.3vw\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset1&Prime; box_shadow_color=\u00a0\u00bbrgba(14,225,244,0.33)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div class=\"sc-7cef46a6-0 dfFUpr\" style=\"text-align: center;\" data-sentry-element=\"Container\" data-sentry-component=\"QuestionAnswer\" data-sentry-source-file=\"index.tsx\"><strong>Dipl\u00f4me en psychoth\u00e9rapie humaniste et formation en psychoth\u00e9rapie sensorimotrice (niveau 1)<\/strong><\/div>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb#contact\u00a0\u00bb button_text=\u00a0\u00bbPrendre rendez-vous avec Maria \u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_bg_color=\u00a0\u00bb#d08678&Prime; button_border_width=\u00a0\u00bb18px\u00a0\u00bb button_border_color=\u00a0\u00bb#d08678&Prime; button_border_radius=\u00a0\u00bb100px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb button_font=\u00a0\u00bbMontserrat|500|||||||\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_margin=\u00a0\u00bb-3px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbCall To Action\u00a0\u00bb module_id=\u00a0\u00bbcontact\u00a0\u00bb module_class=\u00a0\u00bbFRONLY\u00a0\u00bb _builder_version=\u00a0\u00bb4.19.4&Prime; background_color=\u00a0\u00bbrgba(255,255,255,0.87)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2021\/12\/8ioenvmof-i.jpg\u00a0\u00bb background_position=\u00a0\u00bbcenter_left\u00a0\u00bb background_blend=\u00a0\u00bboverlay\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||12px||false|false\u00a0\u00bb border_radii=\u00a0\u00bboff||||\u00a0\u00bb border_color_all=\u00a0\u00bb#0cb7d6&Prime; border_width_bottom=\u00a0\u00bb7px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#d08678&Prime; box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_color=\u00a0\u00bbrgba(12,183,214,0.29)\u00a0\u00bb global_module=\u00a0\u00bb5831&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2560px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb||19px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; header_font=\u00a0\u00bbMontserrat||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb50px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_2_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb44px\u00a0\u00bb max_width=\u00a0\u00bb900px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb1px||3px||false|false\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_font_size_phone=\u00a0\u00bb36px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Centre Fran\u00e7ais de Th\u00e9rapie \u00e0 Barcelone<\/h2>\n<p style=\"text-align: center;\">Contactez un th\u00e9rapeute en remplissant le formulaire ci dessous<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb|auto|-19px|auto|false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb|||\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb||||true|true\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbright\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb5%\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb93%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_contact_form use_spam_service=\u00a0\u00bbon\u00a0\u00bb recaptcha_list=\u00a0\u00bbBCN-0&Prime; email=\u00a0\u00bbbarcelone@centre-pensees.com\u00a0\u00bb use_redirect=\u00a0\u00bbon\u00a0\u00bb redirect_url=\u00a0\u00bb\/message-success\u00a0\u00bb success_message=\u00a0\u00bbMessage envoy\u00e9. Merci\u00a0\u00bb submit_button_text=\u00a0\u00bbEnvoyer la demande\u00a0\u00bb admin_label=\u00a0\u00bbContact Form\u00a0\u00bb module_id=\u00a0\u00bbcontact\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _unique_id=\u00a0\u00bb8fa657a4-cee9-479f-bd3c-cc1dfb574461&Prime; form_field_background_color=\u00a0\u00bbrgba(255,255,255,0.78)\u00a0\u00bb form_field_text_color=\u00a0\u00bb#000000&Prime; title_level=\u00a0\u00bbh2&Prime; title_font=\u00a0\u00bb||||||||\u00a0\u00bb title_text_color=\u00a0\u00bb#000000&Prime; captcha_text_color=\u00a0\u00bb#000000&Prime; form_field_font=\u00a0\u00bbMontserrat||||||||\u00a0\u00bb form_field_line_height=\u00a0\u00bb1.8em\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb23px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#d08678&Prime; button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_radius=\u00a0\u00bb4px\u00a0\u00bb button_font=\u00a0\u00bb|600|||||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x24;||divi||400&Prime; button_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_custom_margin=\u00a0\u00bb-2px||||false|false\u00a0\u00bb button_custom_padding=\u00a0\u00bb7px||7px||true|false\u00a0\u00bb max_width=\u00a0\u00bb800px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_css_text_field=\u00a0\u00bbheight: 20px !important;\u00a0\u00bb border_radii=\u00a0\u00bbon|4px|4px|4px|4px\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb form_background_color=\u00a0\u00bb#ffffff\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_contact_field field_id=\u00a0\u00bbnomnom\u00a0\u00bb field_title=\u00a0\u00bbNom\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; form_field_text_color=\u00a0\u00bb#000000&Prime; form_field_focus_background_color=\u00a0\u00bb#ffffff\u00a0\u00bb form_field_focus_text_color=\u00a0\u00bb#000000&Prime; form_field_line_height=\u00a0\u00bb1.2em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbphophone\u00a0\u00bb field_title=\u00a0\u00bbTel\u00a0\u00bb required_mark=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; form_field_text_color=\u00a0\u00bb#000000&Prime; form_field_line_height=\u00a0\u00bb1.2em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbmaimail\u00a0\u00bb field_title=\u00a0\u00bbAdresse mail\u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; form_field_line_height=\u00a0\u00bb1.2em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbsujjet\u00a0\u00bb field_title=\u00a0\u00bbObjet\u00a0\u00bb field_type=\u00a0\u00bbselect\u00a0\u00bb select_options=\u00a0\u00bb%91{%22value%22:%22Psychoth\u00e9rapie individuelle%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22Th\u00e9rapie EMDR%22,%22checked%22:0,%22dragID%22:0},{%22value%22:%22Th\u00e9rapie de couple%22,%22checked%22:0,%22dragID%22:1},{%22value%22:%22Ateliers \/ Workshops%22,%22checked%22:0,%22dragID%22:2},{%22value%22:%22Bilan Psychologique%22,%22checked%22:0,%22dragID%22:3},{%22value%22:%22Th\u00e9rapie en ligne%22,%22checked%22:0,%22dragID%22:4},{%22value%22:%22Sophrologie%22,%22checked%22:0,%22dragID%22:5},{%22value%22:%22R\u00e9flexologie plantaire%22,%22checked%22:0,%22dragID%22:8},{%22value%22:%22Naturopathie et Fleurs de Bach %22,%22checked%22:0,%22dragID%22:7},{%22value%22:%22Autre (pr\u00e9ciser)%22,%22checked%22:0,%22dragID%22:6}%93&Prime; required_mark=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; form_field_font=\u00a0\u00bb||||||||\u00a0\u00bb form_field_font_size=\u00a0\u00bb15px\u00a0\u00bb form_field_line_height=\u00a0\u00bb1.2em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbdispos\u00a0\u00bb field_title=\u00a0\u00bbVos disponibilit\u00e9s pour une consultation sont plut\u00f4t le&#8230; (plusieurs choix possibles)\u00a0\u00bb field_type=\u00a0\u00bbcheckbox\u00a0\u00bb checkbox_options=\u00a0\u00bb%91{%22value%22:%22Lundi%22,%22checked%22:0,%22dragID%22:-1},{%22dragID%22:0,%22value%22:%22Mardi%22,%22checked%22:0},{%22value%22:%22Mercredi%22,%22checked%22:0,%22dragID%22:1},{%22value%22:%22Jeudi%22,%22checked%22:0,%22dragID%22:2},{%22value%22:%22Vendredi%22,%22checked%22:0,%22dragID%22:3},{%22value%22:%22Samedi%22,%22checked%22:0,%22dragID%22:4},{%22value%22:%22Matin%22,%22checked%22:0,%22dragID%22:5},{%22value%22:%22Autour de midi%22,%22checked%22:0,%22dragID%22:6},{%22value%22:%22Fin de journ\u00e9e%22,%22checked%22:0,%22dragID%22:7}%93&Prime; required_mark=\u00a0\u00bboff\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb conditional_logic=\u00a0\u00bbon\u00a0\u00bb conditional_logic_relation=\u00a0\u00bbon\u00a0\u00bb conditional_logic_rules=\u00a0\u00bb%91{%22field%22:%22objet%22,%22condition%22:%22is not%22,%22value%22:%22Autre (pr\u00e9ciser)%22},{%22field%22:%22objet%22,%22condition%22:%22is not empty%22,%22value%22:%22Psychoth\u00e9rapie individuelle%22}%93&Prime; _builder_version=\u00a0\u00bb4.17.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbMessa\u00a0\u00bb field_title=\u00a0\u00bbQuelques mots au sujet de votre demande\u00a0\u00bb field_type=\u00a0\u00bbtext\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; form_field_line_height=\u00a0\u00bb1.6em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bburl\u00a0\u00bb field_title=\u00a0\u00bburl page: \u00a0\u00bb required_mark=\u00a0\u00bboff\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_free_form=\u00a0\u00bbselector {display: none;}\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][et_pb_blurb title=\u00a0\u00bb930 31 38 88&Prime; use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe090;||divi||400&Prime; icon_color=\u00a0\u00bb#d08678&Prime; image_icon_background_color=\u00a0\u00bbrgba(255,255,255,0.32)\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb16px\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bbMontserrat||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#515151&Prime; header_font_size=\u00a0\u00bb16px\u00a0\u00bb header_line_height=\u00a0\u00bb1.7em\u00a0\u00bb image_icon_custom_padding=\u00a0\u00bb8px|8px|8px|8px|false|false\u00a0\u00bb custom_margin=\u00a0\u00bb||-1px|||\u00a0\u00bb custom_padding=\u00a0\u00bb||10px|||\u00a0\u00bb border_radii_image=\u00a0\u00bbon|100%|100%|100%|100%\u00a0\u00bb border_width_all_image=\u00a0\u00bb2px\u00a0\u00bb border_color_all_image=\u00a0\u00bb#d08678&Prime; icon_font_size=\u00a0\u00bb16px\u00a0\u00bb use_circle=\u00a0\u00bbon\u00a0\u00bb use_circle_border=\u00a0\u00bbon\u00a0\u00bb circle_color=\u00a0\u00bbrgba(255,255,255,0.32)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb image_icon_background_color__sticky_enabled=\u00a0\u00bb#d08678&Prime; image_icon_background_color__sticky=\u00a0\u00bb#d08678&Prime;][\/et_pb_blurb][et_pb_blurb title=\u00a0\u00bbRonda de Sant Antoni, 86 08001 Barcelona\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe081;||divi||400&Prime; icon_color=\u00a0\u00bb#d08678&Prime; image_icon_background_color=\u00a0\u00bbrgba(255,255,255,0.32)\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb16px\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.19.4&Prime; header_level=\u00a0\u00bbh2&Prime; header_font=\u00a0\u00bbMontserrat||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#515151&Prime; header_font_size=\u00a0\u00bb16px\u00a0\u00bb header_line_height=\u00a0\u00bb1.7em\u00a0\u00bb image_icon_custom_padding=\u00a0\u00bb8px|8px|8px|8px|false|false\u00a0\u00bb custom_margin=\u00a0\u00bb||-1px|||\u00a0\u00bb border_radii_image=\u00a0\u00bbon|100%|100%|100%|100%\u00a0\u00bb border_width_all_image=\u00a0\u00bb2px\u00a0\u00bb border_color_all_image=\u00a0\u00bb#d08678&Prime; icon_font_size=\u00a0\u00bb16px\u00a0\u00bb use_circle=\u00a0\u00bbon\u00a0\u00bb use_circle_border=\u00a0\u00bbon\u00a0\u00bb circle_color=\u00a0\u00bbrgba(255,255,255,0.32)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb image_icon_background_color__sticky_enabled=\u00a0\u00bb#d08678&Prime; image_icon_background_color__sticky=\u00a0\u00bb#d08678&Prime;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_code disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.18.0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d47875.71959792756!2d2.1347924489783314!3d41.41247193602935!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x12a4a32ee64aa36b%3A0xbfb0bc60a19db753!2sCentre%20Fran%C3%A7ais%20de%20Th%C3%A9rapie%20%7C%20Centre%20Pens%C3%A9es!5e0!3m2!1sfr!2sfr!4v1665747244605!5m2!1sfr!2sfr\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe>[\/et_pb_code][et_pb_social_media_follow disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb-13px|||||\u00a0\u00bb custom_css_social_icon=\u00a0\u00bbtext-decoration: none !important;\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_social_media_follow_network social_network=\u00a0\u00bbfacebook\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.facebook.com\/centrepensees\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#3b5998&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bblinkedin\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.linkedin.com\/company\/centre-pensees\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#007bb6&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]linkedin[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbinstagram\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.instagram.com\/explore\/tags\/centrepensees\/\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#ea2c59&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centre Pens\u00e9es &#8211; Centre International de th\u00e9rapie \u00e0 Barcelone Mar\u00eda Mart\u00ed Psychoth\u00e9rapie int\u00e9grative, th\u00e9rapie pour adultes et adolescentsJe suis psychoth\u00e9rapeute et je travaille \u00e0 partir d\u2019une approche humaniste et int\u00e9grative, avec un fort ancrage relationnel. J\u2019accompagne des personnes en espagnol et en anglais, et je travaille avec des client\u00b7e\u00b7s locaux et internationaux, dont beaucoup vivent [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8272,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-8274","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mar\u00eda Mart\u00ed Psychologue hispanophone et anglophone \u00e0 Barcelone | Psychologue Fran\u00e7ais \u00e0 Barcelone<\/title>\n<meta name=\"description\" content=\"Marie Marti psychologue espagnol et anglophone \u00e0 barcelone th\u00e9rapie pour adultes et enfants th\u00e9rapie int\u00e9grative\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barcelone.centre-pensees.com\/es\/maria-marti-psicologa-de-habla-hispana-e-inglesa-en-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mar\u00eda Mart\u00ed Psychologue hispanophone et anglophone \u00e0 Barcelone | Psychologue Fran\u00e7ais \u00e0 Barcelone\" \/>\n<meta property=\"og:description\" content=\"Marie Marti psychologue espagnol et anglophone \u00e0 barcelone th\u00e9rapie pour adultes et enfants th\u00e9rapie int\u00e9grative\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barcelone.centre-pensees.com\/es\/maria-marti-psicologa-de-habla-hispana-e-inglesa-en-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Psychologue Fran\u00e7ais \u00e0 Barcelone\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T14:58:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2026\/02\/foto-psicologia-barcelona-psychologist-barcelona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\\\/\",\"url\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\\\/\",\"name\":\"Mar\u00eda Mart\u00ed Psychologue hispanophone et anglophone \u00e0 Barcelone | Psychologue Fran\u00e7ais \u00e0 Barcelone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/foto-psicologia-barcelona-psychologist-barcelona.jpg\",\"datePublished\":\"2026-02-03T08:20:54+00:00\",\"dateModified\":\"2026-03-23T14:58:03+00:00\",\"description\":\"Marie Marti psychologue espagnol et anglophone \u00e0 barcelone th\u00e9rapie pour adultes et enfants th\u00e9rapie int\u00e9grative\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/barcelone.centre-pensees.com\\\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/foto-psicologia-barcelona-psychologist-barcelona.jpg\",\"contentUrl\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/foto-psicologia-barcelona-psychologist-barcelona.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mar\u00eda Mart\u00ed Psychologue hispanophone et anglophone \u00e0 Barcelone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/#website\",\"url\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/\",\"name\":\"Psychologue Fran\u00e7ais \u00e0 Barcelone\",\"description\":\"Centre de psychoth\u00e9rapie \u00e0 Barcelone\",\"publisher\":{\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/#organization\",\"name\":\"Centre Pens\u00e9es\",\"url\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/nobg-pensees-logo-bleu.png\",\"contentUrl\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/nobg-pensees-logo-bleu.png\",\"width\":608,\"height\":545,\"caption\":\"Centre Pens\u00e9es\"},\"image\":{\"@id\":\"https:\\\/\\\/barcelone.centre-pensees.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mar\u00eda Mart\u00ed Psic\u00f3loga espa\u00f1ola e inglesa en Barcelona | Psic\u00f3loga francesa en Barcelona","description":"Marie Marti psic\u00f3loga de habla hispana e inglesa en barcelona terapia para adultos y ni\u00f1os terapia integrativa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barcelone.centre-pensees.com\/es\/maria-marti-psicologa-de-habla-hispana-e-inglesa-en-barcelona\/","og_locale":"es_ES","og_type":"article","og_title":"Mar\u00eda Mart\u00ed Psychologue hispanophone et anglophone \u00e0 Barcelone | Psychologue Fran\u00e7ais \u00e0 Barcelone","og_description":"Marie Marti psychologue espagnol et anglophone \u00e0 barcelone th\u00e9rapie pour adultes et enfants th\u00e9rapie int\u00e9grative","og_url":"https:\/\/barcelone.centre-pensees.com\/es\/maria-marti-psicologa-de-habla-hispana-e-inglesa-en-barcelona\/","og_site_name":"Psychologue Fran\u00e7ais \u00e0 Barcelone","article_modified_time":"2026-03-23T14:58:03+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2026\/02\/foto-psicologia-barcelona-psychologist-barcelona.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/barcelone.centre-pensees.com\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/","url":"https:\/\/barcelone.centre-pensees.com\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/","name":"Mar\u00eda Mart\u00ed Psic\u00f3loga espa\u00f1ola e inglesa en Barcelona | Psic\u00f3loga francesa en Barcelona","isPartOf":{"@id":"https:\/\/barcelone.centre-pensees.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/barcelone.centre-pensees.com\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/#primaryimage"},"image":{"@id":"https:\/\/barcelone.centre-pensees.com\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/#primaryimage"},"thumbnailUrl":"https:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2026\/02\/foto-psicologia-barcelona-psychologist-barcelona.jpg","datePublished":"2026-02-03T08:20:54+00:00","dateModified":"2026-03-23T14:58:03+00:00","description":"Marie Marti psic\u00f3loga de habla hispana e inglesa en barcelona terapia para adultos y ni\u00f1os terapia integrativa","breadcrumb":{"@id":"https:\/\/barcelone.centre-pensees.com\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/barcelone.centre-pensees.com\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/barcelone.centre-pensees.com\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/#primaryimage","url":"https:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2026\/02\/foto-psicologia-barcelona-psychologist-barcelona.jpg","contentUrl":"https:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2026\/02\/foto-psicologia-barcelona-psychologist-barcelona.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/barcelone.centre-pensees.com\/maria-marti-psychologue-hispanophone-et-anglophone-a-barcelone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/barcelone.centre-pensees.com\/"},{"@type":"ListItem","position":2,"name":"Mar\u00eda Mart\u00ed Psychologue hispanophone et anglophone \u00e0 Barcelone"}]},{"@type":"WebSite","@id":"https:\/\/barcelone.centre-pensees.com\/#website","url":"https:\/\/barcelone.centre-pensees.com\/","name":"Psic\u00f3logo franc\u00e9s en Barcelona","description":"Centro de psicoterapia en Barcelona","publisher":{"@id":"https:\/\/barcelone.centre-pensees.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barcelone.centre-pensees.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/barcelone.centre-pensees.com\/#organization","name":"Centro Pens\u00e9es","url":"https:\/\/barcelone.centre-pensees.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/barcelone.centre-pensees.com\/#\/schema\/logo\/image\/","url":"https:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2022\/03\/nobg-pensees-logo-bleu.png","contentUrl":"https:\/\/barcelone.centre-pensees.com\/wp-content\/uploads\/2022\/03\/nobg-pensees-logo-bleu.png","width":608,"height":545,"caption":"Centre Pens\u00e9es"},"image":{"@id":"https:\/\/barcelone.centre-pensees.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/pages\/8274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/comments?post=8274"}],"version-history":[{"count":7,"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/pages\/8274\/revisions"}],"predecessor-version":[{"id":8352,"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/pages\/8274\/revisions\/8352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/media\/8272"}],"wp:attachment":[{"href":"https:\/\/barcelone.centre-pensees.com\/es\/wp-json\/wp\/v2\/media?parent=8274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}